{"id":6888,"date":"2016-05-18T09:41:24","date_gmt":"2016-05-18T08:41:24","guid":{"rendered":"https:\/\/www.lorentz.de\/fr\/products\/submersible-solar-pumps\/"},"modified":"2026-06-19T12:02:34","modified_gmt":"2026-06-19T11:02:34","slug":"pompes-solaires-submersibles","status":"publish","type":"page","link":"https:\/\/www.lorentz.de\/fr\/produits-et-technologie\/types-de-pompes\/pompes-solaires-submersibles\/","title":{"rendered":"Pompes Solaires Submersibles"},"content":{"rendered":"<section class=\"l-section wpb_row height_small color_primary\"><div class=\"l-section-h i-cf\"><div class=\"g-cols offset_medium\"><div class=\" one-half\"><div class=\"wpb_text_column  text-col-max-width valigned large\"><div class=\"wpb_wrapper\">\n<h2 id=\"A\" class=\"notopline\">Pompes \u00e0 eau submersibles \u00e0 \u00e9nergie solaire<\/h2>\n<\/div> <\/div> <\/div><div class=\" one-half\"><div class=\"w-image  align_center animate_afc d1 image_in_a_circle\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz-installing-a-large-system-600x600.jpg\" class=\"attachment-tnail-1x1 size-tnail-1x1\" alt=\"Submersible Solar Pumps\" srcset=\"https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz-installing-a-large-system-600x600.jpg 600w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz-installing-a-large-system-150x150.jpg 150w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz-installing-a-large-system-300x300.jpg 300w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz-installing-a-large-system-768x768.jpg 768w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz-installing-a-large-system-1024x1024.jpg 1024w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz-installing-a-large-system-350x350.jpg 350w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz-installing-a-large-system.jpg 2000w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols offset_medium\"><div class=\" one-half\"><div class=\"wpb_text_column \"><div class=\"wpb_wrapper\">\n<h2>Avantages<\/h2>\n<ul>\n<li>Longue esp\u00e9rance de vie et \u00e9prouv\u00e9 dans le dossier de service<\/li>\n<li><span id=\"result_box\" class=\"\" lang=\"fr\"><span class=\"\">Con\u00e7us pour \u00eatre utilis\u00e9 dans des conditions \u00e9loign\u00e9es et difficiles<\/span><\/span><\/li>\n<li><span id=\"result_box\" class=\"\" lang=\"fr\"><span class=\"\">Conception modulaire intelligente pour un entretien et une r\u00e9paration simple et rentable<\/span><\/span><\/li>\n<li><span id=\"result_box\" class=\"\" lang=\"fr\"><span class=\"\">Moteurs remplis d&rsquo;eau pour la fiabilit\u00e9 et pour \u00e9viter la contamination par l&rsquo;huile<\/span><\/span><\/li>\n<li>Installation simple et rapide<\/li>\n<li>P<span id=\"result_box\" class=\"short_text\" lang=\"fr\"><span class=\"\">hilosophie des pi\u00e8ces de rechange rentable<\/span><\/span><\/li>\n<li><span id=\"result_box\" class=\"short_text\" lang=\"fr\"><span class=\"\">Tr\u00e8s fort retour sur investissement contre le pompage diesel<\/span><\/span><\/li>\n<li><span id=\"result_box\" class=\"\" lang=\"fr\"><span class=\"\">Une large gamme de pompes adapt\u00e9es \u00e0 chaque application et pour optimiser le rendement<\/span><\/span><\/li>\n<\/ul>\n<\/div> <\/div> <\/div><div class=\" one-half\"><div class=\"wpb_text_column \"><div class=\"wpb_wrapper\">\n<h2>Caract\u00e9ristiques<\/h2>\n<ul>\n<li>Con\u00e7us en Allemagne<\/li>\n<li>Mat\u00e9riaux de haute qualit\u00e9 r\u00e9sistants \u00e0 la corrosion<\/li>\n<li><span id=\"result_box\" class=\"short_text\" lang=\"fr\"><span class=\"\">Composants en acier inoxydable coul\u00e9<\/span><\/span><\/li>\n<li><span id=\"result_box\" class=\"\" lang=\"fr\"><span class=\"\">Connexion directe solaire avec options de connexion CA<\/span><\/span><\/li>\n<li>Technologie MPPT pour maximiser la consommation d&rsquo;\u00e9nergie des modules PV<\/li>\n<li>Moteur CC sans balais ECDRIVE, con\u00e7u pour le solaire, avec plus de 90\u2009% d&rsquo;efficacit\u00e9<\/li>\n<li><span id=\"result_box\" class=\"short_text\" lang=\"fr\"><span class=\"\">Enregistreur de donn\u00e9es facultatif<\/span><\/span><\/li>\n<li>Pompes h\u00e9lico\u00efdales: d<span id=\"result_box\" class=\"\" lang=\"fr\"><span class=\"\">es variantes sp\u00e9cifiques \u00e0 la temp\u00e9rature de l&rsquo;eau pour fournir les rendements les plus efficaces<\/span><\/span><\/li>\n<\/ul>\n<\/div> <\/div> <\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium width_full row-fixed-height\"><div class=\"l-section-h i-cf\"><div class=\"g-cols offset_medium\"><div class=\" full-width\"><\/div><\/div><\/div><\/section><!-- Row Backgrounds --><div class=\"upb_bg_img\" data-ultimate-bg=\"url(https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/05\/lorentz_community-with-a-submersible-pump.jpg)\" data-image-id=\"id^9546|url^\/wp-content\/uploads\/2016\/05\/lorentz_community-with-a-submersible-pump.jpg|caption^null|alt^null|title^lorentz_community-with-a-submersible-pump|description^null\" data-ultimate-bg-style=\"vcpb-vz-jquery\" data-bg-img-repeat=\"no-repeat\" data-bg-img-size=\"cover\" data-bg-img-position=\"\" data-parallx_sense=\"8\" data-bg-override=\"full\" data-bg_img_attach=\"fixed\" data-upb-overlay-color=\"\" data-upb-bg-animation=\"\" data-fadeout=\"\" data-bg-animation=\"left-animation\" data-bg-animation-type=\"h\" data-animation-repeat=\"repeat\" data-fadeout-percentage=\"30\" data-parallax-content=\"\" data-parallax-content-sense=\"30\" data-row-effect-mobile-disable=\"true\" data-img-parallax-mobile-disable=\"false\" data-rtl=\"false\"  data-custom-vc-row=\"\"  data-vc=\"5.0.1\"  data-is_old_vc=\"\"  data-theme-support=\"\"   data-overlay=\"false\" data-overlay-color=\"\" data-overlay-pattern=\"\" data-overlay-pattern-opacity=\"\" data-overlay-pattern-size=\"\"    ><\/div><section class=\"l-section wpb_row height_small color_primary\"><div class=\"l-section-h i-cf\"><div class=\"g-cols offset_medium\"><div class=\" full-width\"><div class=\"wpb_text_column \"><div class=\"wpb_wrapper\">\n<h2>Brochure des Produits<\/h2>\n<\/div> <\/div> <\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols offset_medium\"><div class=\" two-thirds\"><div class=\"wpb_text_column  text-col-max-width valigned\"><div class=\"wpb_wrapper\">\n<h3 id=\"3\">Syst\u00e8mes de Pompage Solaire PS2<br \/>\nCentrifuges et H\u00e9lico\u00efdales<\/h3>\n<div id=\"box_spc_nospace\">\n<div class=\"column col23\">\n<p><span id=\"result_box\" class=\"\" lang=\"fr\"><span class=\"\">Les pompes PS2\u00a0LORENTZ sont des produits de haute qualit\u00e9 con\u00e7us pour l&rsquo;approvisionnement en eau potable, l&rsquo;abreuvement du b\u00e9tail, la gestion des \u00e9tangs et les applications d&rsquo;irrigation.<\/span> <span class=\"\">Les syst\u00e8mes de pompes PS2 fournissent l&rsquo;eau de mani\u00e8re \u00e9conomique, propre et fiable, partout.<\/span><\/span><\/p>\n<p>D\u00e9bit max.: 78 m<sup>3<\/sup>\/heure<br \/>\nHauteur max.: 450 m<\/p>\n<\/div>\n<\/div>\n<\/div> <\/div> <div class=\"w-btn-wrapper align_left\"><a class=\"w-btn style_raised size_medium color_primary icon_none\" href=\"\/pdf\/lorentz_ps2_product-brochure_fr.pdf\"><span class=\"w-btn-label\">fran\u00e7ais<\/span><\/a><\/div><div class=\"w-btn-wrapper align_left\"><a class=\"w-btn style_raised size_medium color_primary icon_none\" href=\"\/pdf\/lorentz_ps2_product-brochure_en.pdf\"><span class=\"w-btn-label\">anglais<\/span><\/a><\/div><div class=\"w-btn-wrapper align_left\"><a class=\"w-btn style_raised size_medium color_primary icon_none\" href=\"\/pdf\/lorentz_ps2_product-brochure_es.pdf\"><span class=\"w-btn-label\">espagnol<\/span><\/a><\/div><\/div><div class=\" one-third\"><div class=\"w-image  align_center animate_fade d1\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/05\/lorentz_centrifugal-submersible-family-no-whitespace-350x350.jpg\" class=\"attachment-tnail-1x1-small size-tnail-1x1-small\" alt=\"\" srcset=\"https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/05\/lorentz_centrifugal-submersible-family-no-whitespace-350x350.jpg 350w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/05\/lorentz_centrifugal-submersible-family-no-whitespace-150x150.jpg 150w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small color_alternate\"><div class=\"l-section-h i-cf\"><div class=\"g-cols offset_medium\"><div class=\" two-thirds switched_cols \"><div class=\"wpb_text_column  text-col-max-width valigned\"><div class=\"wpb_wrapper\">\n<h3 id=\"3\">Syst\u00e8mes de Pompage Solaire Centrifuges PSk2<\/h3>\n<div id=\"box_spc_nospace\">\n<div class=\"column col23\">\n<p><span id=\"result_box\" class=\"\" lang=\"fr\"><span class=\"\">Les syst\u00e8mes\u00a0PSk2 LORENTZ sont notre nouvelle g\u00e9n\u00e9ration de pompes \u00e0 eau solaires con\u00e7ues pour fournir le plus grand volume d&rsquo;eau \u00e0 travers une vaste gamme de d\u00e9bits.\u00a0Les pompes PSk2 fonctionnent aussi bien dans les projets d&rsquo;irrigation que dans les applications d&rsquo;eau potable o\u00f9 elles r\u00e9pondent de fa\u00e7on fiable aux demandes les plus exigeantes, \u00e9conomiquement et sans utilisation de combustibles fossiles ou d&rsquo;une connexion au r\u00e9seau.<br \/>\n<\/span><\/span><\/p>\n<p>D\u00e9bit max.: 767 m<sup>3<\/sup>\/heure<br \/>\nHauteur max.: 300\u00a0m<\/p>\n<\/div>\n<\/div>\n<\/div> <\/div> <div class=\"w-btn-wrapper align_left\"><a class=\"w-btn style_raised size_medium color_primary icon_none\" href=\"\/pdf\/lorentz_psk2_product-brochure_fr.pdf\"><span class=\"w-btn-label\">fran\u00e7ais<\/span><\/a><\/div><div class=\"w-btn-wrapper align_left\"><a class=\"w-btn style_raised size_medium color_primary icon_none\" href=\"\/pdf\/lorentz_psk2_product-brochure_en.pdf\"><span class=\"w-btn-label\">anglais<\/span><\/a><\/div><div class=\"w-btn-wrapper align_left\"><a class=\"w-btn style_raised size_medium color_primary icon_none\" href=\"\/pdf\/lorentz_psk2_product-brochure_es.pdf\"><span class=\"w-btn-label\">espagnol<\/span><\/a><\/div><\/div><div class=\" one-third switched_cols\"><div class=\"w-image  align_center animate_fade d1 image_in_a_circle\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/05\/lorentz_centrifugal-submersible-family-350x350.jpg\" class=\"attachment-tnail-1x1-small size-tnail-1x1-small\" alt=\"\" srcset=\"https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/05\/lorentz_centrifugal-submersible-family-350x350.jpg 350w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/05\/lorentz_centrifugal-submersible-family-150x150.jpg 150w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/05\/lorentz_centrifugal-submersible-family-300x300.jpg 300w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/05\/lorentz_centrifugal-submersible-family-600x600.jpg 600w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/05\/lorentz_centrifugal-submersible-family.jpg 709w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small color_primary\"><div class=\"l-section-h i-cf\"><div class=\"g-cols offset_medium\"><div class=\" full-width\"><div class=\"wpb_text_column \"><div class=\"wpb_wrapper\">\n<h2>Pr\u00e9sentation des Produits<\/h2>\n<\/div> <\/div> <\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols offset_medium\"><div class=\" two-thirds\"><div class=\"wpb_text_column  text-col-max-width valigned \"><div class=\"wpb_wrapper\">\n<h3 id=\"1\">Syst\u00e8mes de Pompage Solaire H\u00e9lico\u00efdales PS2<\/h3>\n<div id=\"box_spc_nospace\">\n<div class=\"column col23\">\n<p><span id=\"result_box\" class=\"\" lang=\"fr\"><span class=\"\">Les pompes \u00e0 rotor h\u00e9lico\u00efdal PS2\u00a0LORENTZ sont des produits de haute qualit\u00e9 con\u00e7us pour l&rsquo;approvisionnement en eau potable, l&rsquo;abreuvement du b\u00e9tail et les petites applications d&rsquo;irrigation. <\/span><span class=\"\">Les syst\u00e8mes de pompes \u00e0 rotor h\u00e9lico\u00efdal PS2 fournissent de l&rsquo;eau de mani\u00e8re \u00e9conomique, propre et fiable, partout.<\/span><\/span><\/p>\n<p>D\u00e9bit max.: 3.9\u00a0m<sup>3<\/sup>\/heure<br \/>\nHauteur max.: 450\u00a0m<\/p>\n<\/div>\n<\/div>\n<\/div> <\/div> <div class=\"w-btn-wrapper align_left\"><a class=\"w-btn style_raised size_medium color_primary icon_none\" href=\"\/pdf\/lorentz_ps_hr_general_fr.pdf\"><span class=\"w-btn-label\">fran\u00e7ais<\/span><\/a><\/div><div class=\"w-btn-wrapper align_left\"><a class=\"w-btn style_raised size_medium color_primary icon_none\" href=\"\/pdf\/lorentz_ps_hr_general_en-en.pdf\"><span class=\"w-btn-label\">anglais (m\u00e9trique)<\/span><\/a><\/div><div class=\"w-btn-wrapper align_left\"><a class=\"w-btn style_raised size_medium color_primary icon_none\" href=\"\/pdf\/lorentz_ps_hr_general_en-us.pdf\"><span class=\"w-btn-label\">anglais (EU)<\/span><\/a><\/div><div class=\"w-btn-wrapper align_left\"><a class=\"w-btn style_raised size_medium color_primary icon_none\" href=\"\/pdf\/lorentz_ps_hr_general_es.pdf\"><span class=\"w-btn-label\">espagnol<\/span><\/a><\/div><div class=\"w-btn-wrapper align_left\"><a class=\"w-btn style_raised size_medium color_primary icon_none\" href=\"\/pdf\/lorentz_ps_hr_general_pt.pdf\"><span class=\"w-btn-label\">portugais<\/span><\/a><\/div><\/div><div class=\" one-third\"><div class=\"w-image  align_center animate_fade d1 image_in_a_circle \"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz_hr-family-350x350.jpg\" class=\"attachment-tnail-1x1-small size-tnail-1x1-small\" alt=\"\" srcset=\"https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz_hr-family-350x350.jpg 350w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz_hr-family-150x150.jpg 150w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz_hr-family-300x300.jpg 300w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz_hr-family-768x768.jpg 768w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz_hr-family-1024x1024.jpg 1024w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz_hr-family-600x600.jpg 600w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz_hr-family.jpg 1650w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small color_alternate\"><div class=\"l-section-h i-cf\"><div class=\"g-cols offset_medium\"><div class=\" two-thirds switched_cols\"><div class=\"wpb_text_column  text-col-max-width valigned \"><div class=\"wpb_wrapper\">\n<h3 id=\"2\">Syst\u00e8mes de Pompage Solaire Centrifuges PS2<\/h3>\n<div id=\"box_spc_nospace\">\n<div class=\"column col23\">\n<p>Les pompes centrifuges PS2 LORENTZ sont des <span id=\"result_box\" class=\"\" lang=\"fr\"><span class=\"\"> produits de haute qualit\u00e9 con\u00e7us pour<\/span><\/span> un <span id=\"result_box\" class=\"\" lang=\"fr\"><span class=\"\">approvisionnement en eau potable avec des d\u00e9bits \u00e9lev\u00e9s,\u00a0l&rsquo;abreuvement du b\u00e9tail, la gestion des \u00e9tangs et les applications d&rsquo;irrigation. Les pompes centrifuges PS2 fournissent de grands volumes d&rsquo;eau \u00e9conomiquement, sans pollution, n&rsquo;importe o\u00f9.<br \/>\n<\/span><\/span><\/p>\n<p>D\u00e9bit max.: 79\u00a0m<sup>3<\/sup>\/heure<br \/>\nHauteur max: 160\u00a0m<\/p>\n<\/div>\n<\/div>\n<\/div> <\/div> <div class=\"w-btn-wrapper align_left\"><a class=\"w-btn style_raised size_medium color_primary icon_none\" href=\"\/pdf\/lorentz_ps_c_general_fr.pdf\"><span class=\"w-btn-label\">fran\u00e7ais<\/span><\/a><\/div><div class=\"w-btn-wrapper align_left\"><a class=\"w-btn style_raised size_medium color_primary icon_none\" href=\"\/pdf\/lorentz_ps_c_general_en-en.pdf\"><span class=\"w-btn-label\">anglais (m\u00e9trique)<\/span><\/a><\/div><div class=\"w-btn-wrapper align_left\"><a class=\"w-btn style_raised size_medium color_primary icon_none\" href=\"\/pdf\/lorentz_ps_c_general_en-us.pdf\"><span class=\"w-btn-label\">anglais (EU)<\/span><\/a><\/div><div class=\"w-btn-wrapper align_left\"><a class=\"w-btn style_raised size_medium color_primary icon_none\" href=\"\/pdf\/lorentz_ps_c_general_es.pdf\"><span class=\"w-btn-label\">espagnol<\/span><\/a><\/div><div class=\"w-btn-wrapper align_left\"><a class=\"w-btn style_raised size_medium color_primary icon_none\" href=\"\/pdf\/lorentz_ps_c_general_pt.pdf\"><span class=\"w-btn-label\">portugais<\/span><\/a><\/div><\/div><div class=\" one-third switched_cols\"><div class=\"w-image  align_center animate_fade d1 image_in_a_circle\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"350\" src=\"https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/05\/lorentz_centrifugal-submersible-ps-family-350x350.jpg\" class=\"attachment-tnail-1x1-small size-tnail-1x1-small\" alt=\"\" srcset=\"https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/05\/lorentz_centrifugal-submersible-ps-family-350x350.jpg 350w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/05\/lorentz_centrifugal-submersible-ps-family-150x150.jpg 150w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_auto color_primary sticky_at_bottom sticky_at_bottom_teaser\"><div class=\"l-section-h i-cf\"><div class=\"g-cols offset_medium\"><div class=\" one-quarter\"><div class=\"wpb_text_column  sticky_at_bottom_active sticky_at_bottom_downloads\"><div class=\"wpb_wrapper\"><p>Products &amp; Technology<\/p><\/div> <\/div> <\/div><div class=\" one-quarter\"><div class=\"wpb_text_column  sticky_at_bottom_active sticky_at_bottom_case_studies\"><div class=\"wpb_wrapper\"><p>Case Studies<\/p><\/div> <\/div> <\/div><div class=\" one-quarter no_display\"><div class=\"wpb_text_column  sticky_at_bottom_active sticky_at_bottom_references\"><div class=\"wpb_wrapper\"><p>References<\/p><\/div> <\/div> <\/div><div class=\" one-quarter\"><div class=\"wpb_text_column  sticky_at_bottom_active buy_lorentz_pumps\"><div class=\"wpb_wrapper\"><p>Buy LORENTZ pumps<\/p><\/div> <\/div> <\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_auto color_primary sticky_at_bottom sticky_at_bottom_details sticky_at_bottom_downloads\"><div class=\"l-section-h i-cf\"><div class=\"g-cols offset_medium\"><div class=\" full-width\"><div class=\"wpb_text_column \"><div class=\"wpb_wrapper\">\n<h3>Produits &amp; Technologie<\/h3>\n<\/div> <\/div> <div class=\"g-cols wpb_row offset_medium vc_inner \"><div class=\" one-quarter\"><div class=\"w-image  align_center animate_fade d1 image_in_a_circle white\"><a href=\"\/fr\/produits-et-technologie\/produits\/systemes-de-pompage-solaire-ps2\/\" title=\"\" target=\"\" rel=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/ps2-large-whitespace-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/ps2-large-whitespace-150x150.jpg 150w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/ps2-large-whitespace-300x300.jpg 300w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/ps2-large-whitespace-768x768.jpg 768w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/ps2-large-whitespace-1024x1024.jpg 1024w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/ps2-large-whitespace-350x350.jpg 350w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/ps2-large-whitespace-600x600.jpg 600w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/ps2-large-whitespace.jpg 1500w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><\/div><div class=\"wpb_text_column \"><div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column \">\n<div class=\"wpb_wrapper\">\n<p style=\"text-align: center\"><strong><a href=\"\/fr\/produits-et-technologie\/produits\/systemes-de-pompage-solaire-ps2\/\">Syst\u00e8mes de Pompage Solaire PS2<\/a><br \/>\n<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div> <\/div> <\/div><div class=\" one-quarter\"><div class=\"w-image  align_center animate_fade d1 image_in_a_circle white\"><a href=\"\/fr\/produits-et-technologie\/technologie\/efficacite\/\" title=\"\" target=\"\" rel=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.lorentz.de\/wp-content\/uploads\/2014\/10\/lorentz_efficiency-in-circle-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.lorentz.de\/wp-content\/uploads\/2014\/10\/lorentz_efficiency-in-circle-150x150.jpg 150w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2014\/10\/lorentz_efficiency-in-circle-300x300.jpg 300w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2014\/10\/lorentz_efficiency-in-circle-768x768.jpg 768w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2014\/10\/lorentz_efficiency-in-circle-1024x1024.jpg 1024w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2014\/10\/lorentz_efficiency-in-circle-350x350.jpg 350w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2014\/10\/lorentz_efficiency-in-circle-600x600.jpg 600w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2014\/10\/lorentz_efficiency-in-circle.jpg 1240w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><\/div><div class=\"wpb_text_column \"><div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column \">\n<div class=\"wpb_wrapper\">\n<p style=\"text-align: center\"><strong><a href=\"\/fr\/produits-et-technologie\/technologie\/efficacite\/\">Efficacit\u00e9<\/a><br \/>\n<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div> <\/div> <\/div><div class=\" one-quarter\"><div class=\"w-image  align_center animate_fade d1 image_in_a_circle white_thin\"><a href=\"\/fr\/produits-et-technologie\/technologie\/experience-lorentz\/\" title=\"\" target=\"\" rel=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz-connected--150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz-connected--150x150.jpg 150w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz-connected--300x300.jpg 300w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz-connected--768x768.jpg 768w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz-connected--1024x1024.jpg 1024w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz-connected--350x350.jpg 350w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz-connected--600x600.jpg 600w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><\/div><div class=\"wpb_text_column \"><div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column \">\n<div class=\"wpb_wrapper\">\n<p style=\"text-align: center\"><strong><a href=\"\/fr\/produits-et-technologie\/technologie\/experience-lorentz\/\">Exp\u00e9rience LORENTZ<\/a><br \/>\n<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div> <\/div> <\/div><div class=\" one-quarter\"><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_auto color_primary sticky_at_bottom sticky_at_bottom_details sticky_at_bottom_case_studies\"><div class=\"l-section-h i-cf\"><div class=\"g-cols offset_medium\"><div class=\" full-width\"><div class=\"wpb_text_column \"><div class=\"wpb_wrapper\">\n<h3>\u00c9tudes de Cas<\/h3>\n<\/div> <\/div> <div class=\"g-cols wpb_row offset_medium vc_inner \"><div class=\" one-quarter\"><\/div><div class=\" one-quarter\"><\/div><div class=\" one-quarter\"><\/div><div class=\" one-quarter\"><\/div><\/div><div class=\"wpb_text_column  vc_custom_1484741527133\"><div class=\"wpb_wrapper\">\n<p><a href=\"\/fr\/solutions\/etudes-de-cas\/\">toutes les \u00e9tudes de cas<\/a><\/p>\n<\/div> <\/div> <\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_auto color_primary sticky_at_bottom sticky_at_bottom_details sticky_at_bottom_references\"><div class=\"l-section-h i-cf\"><div class=\"g-cols offset_medium\"><div class=\" full-width\"><div class=\"wpb_text_column \"><div class=\"wpb_wrapper\">\n<h3>R\u00e9f\u00e9rences<\/h3>\n<\/div> <\/div> <div class=\"g-cols wpb_row offset_medium vc_inner \"><div class=\" one-quarter\"><div class=\"w-image  align_center animate_fade d1 image_in_a_circle white\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz_grid-connected-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz_grid-connected-150x150.jpg 150w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz_grid-connected-300x300.jpg 300w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz_grid-connected-768x768.jpg 768w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz_grid-connected-1024x1024.jpg 1024w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz_grid-connected-350x350.jpg 350w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz_grid-connected-600x600.jpg 600w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz_grid-connected.jpg 1600w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><div class=\"wpb_text_column \"><div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column \">\n<div class=\"wpb_wrapper\">\n<p style=\"text-align: center\"><strong>PS2-600 Drinking Water Supply for Farming<\/strong><br \/>\nTanzania<br \/>\n[Dummy]\n<\/div>\n<\/div>\n<\/div> <\/div> <\/div><div class=\" one-quarter\"><div class=\"w-image  align_center animate_fade d1 image_in_a_circle white\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/02\/lorentz_india-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/02\/lorentz_india-150x150.jpg 150w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/02\/lorentz_india-350x350.jpg 350w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/02\/lorentz_india-600x600.jpg 600w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><div class=\"wpb_text_column \"><div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column \">\n<div class=\"wpb_wrapper\">\n<p style=\"text-align: center\"><strong>PS2-1200 Drinking Water Supply for Cattle<\/strong><br \/>\nKenya<br \/>\n[Dummy]\n<\/div>\n<\/div>\n<\/div> <\/div> <\/div><div class=\" one-quarter\"><div class=\"w-image  align_center animate_fade d1 image_in_a_circle white\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz_accessories-family-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz_accessories-family-150x150.jpg 150w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz_accessories-family-300x300.jpg 300w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz_accessories-family-768x768.jpg 768w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz_accessories-family-1024x1024.jpg 1024w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz_accessories-family-350x350.jpg 350w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz_accessories-family-600x600.jpg 600w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2016\/10\/lorentz_accessories-family.jpg 1600w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><div class=\"wpb_text_column \"><div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column \">\n<div class=\"wpb_wrapper\">\n<p style=\"text-align: center\"><strong>PS2-1800 Drinking Water Supply for Cattle<\/strong><br \/>\nMozambique<br \/>\n[Dummy]\n<\/div>\n<\/div>\n<\/div> <\/div> <\/div><div class=\" one-quarter\"><div class=\"w-image  align_center animate_fade d1 image_in_a_circle white\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.lorentz.de\/wp-content\/uploads\/2014\/10\/LOR_LandingPage_LargeSystem-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.lorentz.de\/wp-content\/uploads\/2014\/10\/LOR_LandingPage_LargeSystem-150x150.jpg 150w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2014\/10\/LOR_LandingPage_LargeSystem-300x300.jpg 300w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2014\/10\/LOR_LandingPage_LargeSystem-768x768.jpg 768w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2014\/10\/LOR_LandingPage_LargeSystem-1024x1024.jpg 1024w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2014\/10\/LOR_LandingPage_LargeSystem-350x350.jpg 350w, https:\/\/www.lorentz.de\/wp-content\/uploads\/2014\/10\/LOR_LandingPage_LargeSystem-600x600.jpg 600w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><div class=\"wpb_text_column \"><div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column \">\n<div class=\"wpb_wrapper\">\n<p style=\"text-align: center\"><strong>PS2-4000 Pivot Irrigation<\/strong><br \/>\nInde<br \/>\n[Dummy]\n<\/div>\n<\/div>\n<\/div> <\/div> <\/div><\/div><div class=\"wpb_text_column  vc_custom_1482331131475\"><div class=\"wpb_wrapper\">\n<p><a href=\"\/fr\/references\/\">plus de r\u00e9f\u00e9rences<\/a><\/p>\n<\/div> <\/div> <\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"Pompes \u00e0 eau submersibles \u00e0 \u00e9nergie solaire Avantages Longue esp\u00e9rance de vie et \u00e9prouv\u00e9 dans le dossier de service Con\u00e7us pour \u00eatre utilis\u00e9 dans des conditions \u00e9loign\u00e9es et difficiles Conception modulaire intelligente pour un entretien et une r\u00e9paration simple et...","protected":false},"author":1,"featured_media":0,"parent":10121,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-6888","page","type-page","status-publish","hentry","floatton-article"],"_links":{"self":[{"href":"https:\/\/www.lorentz.de\/fr\/wp-json\/wp\/v2\/pages\/6888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lorentz.de\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.lorentz.de\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.lorentz.de\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lorentz.de\/fr\/wp-json\/wp\/v2\/comments?post=6888"}],"version-history":[{"count":37,"href":"https:\/\/www.lorentz.de\/fr\/wp-json\/wp\/v2\/pages\/6888\/revisions"}],"predecessor-version":[{"id":43448,"href":"https:\/\/www.lorentz.de\/fr\/wp-json\/wp\/v2\/pages\/6888\/revisions\/43448"}],"up":[{"embeddable":true,"href":"https:\/\/www.lorentz.de\/fr\/wp-json\/wp\/v2\/pages\/10121"}],"wp:attachment":[{"href":"https:\/\/www.lorentz.de\/fr\/wp-json\/wp\/v2\/media?parent=6888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}